{"id":1709,"date":"2023-01-25T18:00:22","date_gmt":"2023-01-25T17:00:22","guid":{"rendered":"https:\/\/turismo.segorbe.es\/seminario\/"},"modified":"2023-09-16T15:17:24","modified_gmt":"2023-09-16T14:17:24","slug":"seminario","status":"publish","type":"page","link":"https:\/\/turismo.segorbe.es\/de\/patrimonio\/patrimonio-religioso\/seminario\/","title":{"rendered":"Priesterseminar"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":2744,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1709","page","type-page","status-publish","hentry"],"acf":{"contenido":[{"acf_fc_layout":"titulo","titulo_pequeno":true,"fondo":""},{"acf_fc_layout":"galeria","full":true,"imagenes":[1710,3169,3172,3175,3178],"fondo":""},{"acf_fc_layout":"texto","diseno":"peq","texto":"Die Erbauung des Priesterseminars erfolgte im 17. Jahrhundert und geh\u00f6rte zu dem Jesuitenorden bis zu ihrer Vertreibung im Jahre 1771. Schule und Wohnheim wurden im doppelten Fl\u00fcgel zum Garten hin strukturiert, dessen Mittelst\u00fcck durch eine gro\u00dfe Freitreppe gekennzeichnet und mit einer Kuppel vollendet ist.\u00a0\u00a0\u00a0 Zwischen dieser und der Hauptfassade liegt ein doppelter Kreuzgang und die Kirche. Auch heutzutage hebt sie sich noch mit ihrem Grundriss eines lateinischen Kreuzes, dem einzigen Kirchenschiff und einer Trib\u00fcne \u00fcber der Kapelle hervor. Der Komplex ist dominiert durch die gro\u00dfe Kuppel, mit Fenstern im Tambour und ausgiebiger Schnitzerei, sowie Sgraffito. Die Hauptfassade passt sich an die unregelm\u00e4\u00dfig verlaufende Stra\u00dfe an, die an der Au\u00dfenmauer entlang f\u00fchrt. Das Tor der Kirche, sowie das Tor mit Zugang zur Stra\u00dfe fallen durch ihre N\u00fcchternheit auf. Das abgeflachte Tor wird von korinthischen S\u00e4ulen flankiert und der Hauptsims umrahmt den gro\u00dfen Balkon.","fondo":""}]},"_links":{"self":[{"href":"https:\/\/turismo.segorbe.es\/de\/wp-json\/wp\/v2\/pages\/1709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turismo.segorbe.es\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/turismo.segorbe.es\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/turismo.segorbe.es\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turismo.segorbe.es\/de\/wp-json\/wp\/v2\/comments?post=1709"}],"version-history":[{"count":0,"href":"https:\/\/turismo.segorbe.es\/de\/wp-json\/wp\/v2\/pages\/1709\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/turismo.segorbe.es\/de\/wp-json\/wp\/v2\/pages\/2744"}],"wp:attachment":[{"href":"https:\/\/turismo.segorbe.es\/de\/wp-json\/wp\/v2\/media?parent=1709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}